{"id":20091,"date":"2025-11-24T12:22:35","date_gmt":"2025-11-24T11:22:35","guid":{"rendered":"https:\/\/seismosoft.com\/?post_type=product&#038;p=20091"},"modified":"2026-09-02T15:15:02","modified_gmt":"2026-09-02T13:15:02","slug":"seismosignal-3d-usb-dongle","status":"publish","type":"product","link":"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/","title":{"rendered":"SeismoSignal 3D + USB Dongle"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>SeismoSignal 3D costituisce un modo semplice ed efficiente per elaborare i dati di moto forte in 2 (X+Y) o 3 (X+Y+Z) dimensioni, offrendo un&#8217;interfaccia visiva di facile utilizzo e la capacit\u00e0 di derivare una serie di parametri del movimento del suolo spesso richiesti da ingegneri sismici e sismologi.<\/p>\n<p>Il programma \u00e8 in grado di leggere accelerogrammi salvati in diversi formati di file di testo, che possono poi essere filtrati e corretti nella linea di base (baseline correction). Per quest&#8217;ultima possono essere utilizzati polinomi fino al 3\u00b0 ordine, mentre sono disponibili tre diversi tipi di filtri digitali, tutti in grado di eseguire filtraggi passa-alto, passa-basso, passa-banda e blocca-banda (bandstop).<\/p>\n<p>Inoltre, \u00e8 possibile aprire automaticamente file zip contenenti le registrazioni di tutte e tre le componenti scaricate dall&#8217;European Strong Motion Database (ESM) o dai database PEER Ground Motion (NGA-West 2 e NGA-East).<\/p>\n<p>Infine, grazie alla sua completa integrazione con l&#8217;ambiente Windows, SeismoSignal 3D consente di copiare i risultati numerici e grafici in qualsiasi applicazione Windows (ad es. MS Excel, MS Word, ecc.), evidenziando che i grafici delle caratteristiche possono essere interamente personalizzati all&#8217;interno del programma stesso.<\/p>\n<ul>\n<li>Spettri di risposta indipendenti dall&#8217;orientamento, RotD100, RotD50, RotD00 e RotDXX per qualsiasi valore di percentile<\/li>\n<li>Grafici dell&#8217;orbita (Orbit Plots)<\/li>\n<li>Intensit\u00e0 di Arias (Ia) per tutte e tre le componenti X, Y e Z<\/li>\n<li>Velocit\u00e0 assoluta cumulativa (CAV) per tutte e tre le componenti X, Y e Z<\/li>\n<li>Valori di picco dell&#8217;accelerazione al suolo (PGA) per tutte e tre le componenti X, Y e Z<\/li>\n<li>Valori di picco dell&#8217;accelerazione al suolo (PGA) per gli spettri RotD100 e RotD00<\/li>\n<li>Valori di picco della velocit\u00e0 al suolo (PGV) per tutte e tre le componenti X, Y e Z<\/li>\n<li>Valori di picco della velocit\u00e0 al suolo (PGV) per gli spettri RotD100 e RotD00<\/li>\n<li>Valori di picco dello spostamento al suolo (PGD) per tutte e tre le componenti X, Y e Z<\/li>\n<li>Valori di picco dello spostamento al suolo (PGD) per gli spettri RotD100 e RotD00<\/li>\n<\/ul>\n<p>Scopri di pi\u00f9 sulle <a href=\"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d\/\">caratteristiche di SeismoSignal 3D<\/a> o scarica la versione di prova gratuita:<\/p>\n<p><a title=\"Download\" href=\"https:\/\/seismosoft.com\/support\/seismosignal-3d-support\/\">&gt; SeismoSignal 3D<\/a><\/p>\n<\/div><div class=\"fusion-modal modal fade modal-1 sSignal3DSup\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"modal-heading-1\" aria-hidden=\"true\" style=\"--awb-border-color:#03a9f4;--awb-background:#ffffff;\"><div class=\"modal-dialog modal-lg\" role=\"document\"><div class=\"modal-content fusion-modal-content\"><div class=\"modal-header\"><button class=\"close\" type=\"button\" data-dismiss=\"modal\" aria-hidden=\"true\" aria-label=\"Close\">&times;<\/button><h3 class=\"modal-title\" id=\"modal-heading-1\" data-dismiss=\"modal\" aria-hidden=\"true\">SeismoSignal 3D Manutenzione &amp; Supporto<\/h3><\/div><div class=\"modal-body fusion-clearfix\">\n<p>Ottieni il pacchetto SeismoSignal 3D Manutenzione &amp; Supporto per 12 mesi e ricevi:<\/p>\n<ul>\n<li>Supporto in corsia preferenziale<\/li>\n<li>Nuovi rilasci e versioni del prodotto<\/li>\n<\/ul>\n<p class=\"supNote\">Valido per i clienti che dispongono di licenze attive della versione corrente del software al momento dell&#8217;acquisto del Pacchetto di Supporto<\/p>\n<p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><span class=\"woocommerce-Price-amount amount\"><bdi>112.50<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span> <small class=\"woocommerce-price-suffix\">(Si applicano i costi IVA ai clienti italiani)<\/small><a href=\"\/it\/wp-json\/wp\/v2\/product\/20091?add-to-cart=15317\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_15317\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"15317\" data-product_sku=\"ssign3df\" aria-label=\"Aggiungi al carrello: &quot;SeismoSignal 3D Support&quot;\" rel=\"nofollow\" data-success_message=\"&quot;SeismoSignal 3D Support&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Aggiungi al carrello<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_15317\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p>\n<\/div><div class=\"modal-footer\"><button class=\"fusion-button button-default button-medium button default medium\" type=\"button\" data-dismiss=\"modal\">Close<\/button><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>SeismoSignal 3D costituisce un modo semplice ed efficiente per elaborare i dati di moto forte in 2 (X+Y) o 3 (X+Y+Z) dimensioni, offrendo un&#8217;interfaccia visiva di facile utilizzo e la capacit\u00e0 di derivare una serie di parametri del movimento del suolo spesso richiesti da ingegneri sismici e sismologi.<\/p>\n<p>Una chiave hardware Dongle USB verr\u00e0 inviata tramite posta ordinaria. Il Dongle USB consente di utilizzare il software su diverse workstation, ma non contemporaneamente. Il costo aggiuntivo di 100\u20ac include le spese di spedizione del dongle USB. Il dongle USB viene solitamente spedito entro 1-2 giorni lavorativi dalla ricezione del pagamento. Nel caso in cui si desideri la versione con codice prodotto, \u00e8 disponibile una <a href=\"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d\/\">Licenza per Singola Workstation<\/a> che si attiva immediatamente e non comporta costi aggiuntivi, e una <a href=\"https:\/\/seismosoft.com\/it\/prodotto\/20075\/\">Licenza di Rete<\/a> che consente di utilizzare FRP Designer su pi\u00f9 workstation in una rete utilizzando un unico codice prodotto.<\/p>\n<p>[fusion_fontawesome icon=\"fa-user fas\" size=\"18px\" flip=\"\" rotate=\"\" spin=\"no\" link=\"\/it\/product\/frp-designer\/\" linktarget=\"_self\" alignment=\"\" hide_on_mobile=\"small-visibility,medium-visibility,large-visibility\" sticky_display=\"normal,sticky\" class=\"\" id=\"\" margin_top=\"\" margin_right=\"\" margin_bottom=\"\" margin_left=\"\" iconcolor=\"#1b9af7\" iconcolor_hover=\"\" circle=\"\" bg_size=\"-1\" circlecolor=\"#ffffff\" circlecolor_hover=\"#1b9af7\" circlebordersize=\"\" circlebordercolor=\"#ffffff\" circlebordercolor_hover=\"#ffffff\" icon_hover_type=\"\" animation_type=\"\" animation_direction=\"left\" animation_speed=\"0.3\" animation_offset=\"\"][\/fusion_fontawesome]Ottieni <a href=\"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d\/\">SeismoSignal 3D Versione Workstation<\/a>.<\/p>\n<p>[fusion_fontawesome icon=\"fa-network-wired fas\" size=\"18px\" flip=\"\" rotate=\"\" spin=\"no\" link=\"\/it\/product\/frp-designer-network\/\" linktarget=\"_self\" alignment=\"\" hide_on_mobile=\"small-visibility,medium-visibility,large-visibility\" sticky_display=\"normal,sticky\" class=\"\" id=\"\" margin_top=\"\" margin_right=\"\" margin_bottom=\"\" margin_left=\"\" iconcolor=\"#1b9af7\" iconcolor_hover=\"\" circle=\"\" bg_size=\"-1\" circlecolor=\"#ffffff\" circlecolor_hover=\"#1b9af7\" circlebordersize=\"\" circlebordercolor=\"#ffffff\" circlebordercolor_hover=\"#ffffff\" icon_hover_type=\"\" animation_type=\"\" animation_direction=\"left\" animation_speed=\"0.3\" animation_offset=\"\"][\/fusion_fontawesome]Ottieni <a href=\"https:\/\/seismosoft.com\/it\/prodotto\/20075\/\">SeismoSignal 3D Versione Rete<\/a>.<\/p>\n<p>Ottieni il [fusion_modal_text_link name=\"sSignal3DSup\" class=\"\" id=\"\"]pacchetto Manutenzione e Supporto[\/fusion_modal_text_link] (idoneo per il supporto premium pi\u00f9 12 mesi di aggiornamenti gratuiti)<\/p>\n","protected":false},"featured_media":19676,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[133],"product_tag":[126],"class_list":["post-20091","product","type-product","status-publish","has-post-thumbnail","product_cat-dongles","product_tag-apps","first","instock","downloadable","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SeismoSignal 3D + USB Dongle - Seismosoft<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SeismoSignal 3D + USB Dongle - Seismosoft\" \/>\n<meta property=\"og:description\" content=\"SeismoSignal 3D costituisce un modo semplice ed efficiente per elaborare i dati di moto forte in 2 (X+Y) o 3 (X+Y+Z) dimensioni, offrendo un&#039;interfaccia visiva di facile utilizzo e la capacit\u00e0 di derivare una serie di parametri del movimento del suolo spesso richiesti da ingegneri sismici e sismologi.  Una chiave hardware Dongle USB verr\u00e0 inviata tramite posta ordinaria. Il Dongle USB consente di utilizzare il software su diverse workstation, ma non contemporaneamente. Il costo aggiuntivo di 100\u20ac include le spese di spedizione del dongle USB. Il dongle USB viene solitamente spedito entro 1-2 giorni lavorativi dalla ricezione del pagamento. Nel caso in cui si desideri la versione con codice prodotto, \u00e8 disponibile una Licenza per Singola Workstation che si attiva immediatamente e non comporta costi aggiuntivi, e una Licenza di Rete che consente di utilizzare FRP Designer su pi\u00f9 workstation in una rete utilizzando un unico codice prodotto.  Ottieni SeismoSignal 3D Versione Workstation.  Ottieni SeismoSignal 3D Versione Rete.  Ottieni il (idoneo per il supporto premium pi\u00f9 12 mesi di aggiornamenti gratuiti)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/\" \/>\n<meta property=\"og:site_name\" content=\"Seismosoft\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seismoSoft\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T13:15:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seismosoft.com\/wp-content\/uploads\/2023\/11\/seissmosignal-3D-v2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Seismosoft\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/prodotto\\\/seismosignal-3d-usb-dongle\\\/\",\"url\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/prodotto\\\/seismosignal-3d-usb-dongle\\\/\",\"name\":\"SeismoSignal 3D + USB Dongle - Seismosoft\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/prodotto\\\/seismosignal-3d-usb-dongle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/prodotto\\\/seismosignal-3d-usb-dongle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seismosoft.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/seissmosignal-3D-v2.webp\",\"datePublished\":\"2025-11-24T11:22:35+00:00\",\"dateModified\":\"2026-09-02T13:15:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/prodotto\\\/seismosignal-3d-usb-dongle\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seismosoft.com\\\/it\\\/prodotto\\\/seismosignal-3d-usb-dongle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/prodotto\\\/seismosignal-3d-usb-dongle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seismosoft.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/seissmosignal-3D-v2.webp\",\"contentUrl\":\"https:\\\/\\\/seismosoft.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/seissmosignal-3D-v2.webp\",\"width\":600,\"height\":600,\"caption\":\"SeismoSignal 3D\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/prodotto\\\/seismosignal-3d-usb-dongle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acquista software per la valutazione e il rinforzo strutturale\",\"item\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SeismoSignal 3D + USB Dongle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/\",\"name\":\"Seismosoft\",\"description\":\"Earthquake Engineering Software Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/#organization\",\"name\":\"Seismosoft\",\"url\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seismosoft.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/seismosoft-logox2.webp\",\"contentUrl\":\"https:\\\/\\\/seismosoft.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/seismosoft-logox2.webp\",\"width\":406,\"height\":100,\"caption\":\"Seismosoft\"},\"image\":{\"@id\":\"https:\\\/\\\/seismosoft.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seismoSoft\\\/\",\"https:\\\/\\\/x.com\\\/Seismosoft\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seismosoft\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Seismosoft\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SeismoSignal 3D + USB Dongle - Seismosoft","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/","og_locale":"it_IT","og_type":"article","og_title":"SeismoSignal 3D + USB Dongle - Seismosoft","og_description":"SeismoSignal 3D costituisce un modo semplice ed efficiente per elaborare i dati di moto forte in 2 (X+Y) o 3 (X+Y+Z) dimensioni, offrendo un'interfaccia visiva di facile utilizzo e la capacit\u00e0 di derivare una serie di parametri del movimento del suolo spesso richiesti da ingegneri sismici e sismologi.  Una chiave hardware Dongle USB verr\u00e0 inviata tramite posta ordinaria. Il Dongle USB consente di utilizzare il software su diverse workstation, ma non contemporaneamente. Il costo aggiuntivo di 100\u20ac include le spese di spedizione del dongle USB. Il dongle USB viene solitamente spedito entro 1-2 giorni lavorativi dalla ricezione del pagamento. Nel caso in cui si desideri la versione con codice prodotto, \u00e8 disponibile una Licenza per Singola Workstation che si attiva immediatamente e non comporta costi aggiuntivi, e una Licenza di Rete che consente di utilizzare FRP Designer su pi\u00f9 workstation in una rete utilizzando un unico codice prodotto.  Ottieni SeismoSignal 3D Versione Workstation.  Ottieni SeismoSignal 3D Versione Rete.  Ottieni il (idoneo per il supporto premium pi\u00f9 12 mesi di aggiornamenti gratuiti)","og_url":"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/","og_site_name":"Seismosoft","article_publisher":"https:\/\/www.facebook.com\/seismoSoft\/","article_modified_time":"2026-09-02T13:15:02+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/seismosoft.com\/wp-content\/uploads\/2023\/11\/seissmosignal-3D-v2.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@Seismosoft","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/","url":"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/","name":"SeismoSignal 3D + USB Dongle - Seismosoft","isPartOf":{"@id":"https:\/\/seismosoft.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/#primaryimage"},"image":{"@id":"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/#primaryimage"},"thumbnailUrl":"https:\/\/seismosoft.com\/wp-content\/uploads\/2023\/11\/seissmosignal-3D-v2.webp","datePublished":"2025-11-24T11:22:35+00:00","dateModified":"2026-09-02T13:15:02+00:00","breadcrumb":{"@id":"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/#primaryimage","url":"https:\/\/seismosoft.com\/wp-content\/uploads\/2023\/11\/seissmosignal-3D-v2.webp","contentUrl":"https:\/\/seismosoft.com\/wp-content\/uploads\/2023\/11\/seissmosignal-3D-v2.webp","width":600,"height":600,"caption":"SeismoSignal 3D"},{"@type":"BreadcrumbList","@id":"https:\/\/seismosoft.com\/it\/prodotto\/seismosignal-3d-usb-dongle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seismosoft.com\/it\/"},{"@type":"ListItem","position":2,"name":"Acquista software per la valutazione e il rinforzo strutturale","item":"https:\/\/seismosoft.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"SeismoSignal 3D + USB Dongle"}]},{"@type":"WebSite","@id":"https:\/\/seismosoft.com\/it\/#website","url":"https:\/\/seismosoft.com\/it\/","name":"Seismosoft","description":"Earthquake Engineering Software Solutions","publisher":{"@id":"https:\/\/seismosoft.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seismosoft.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/seismosoft.com\/it\/#organization","name":"Seismosoft","url":"https:\/\/seismosoft.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/seismosoft.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/seismosoft.com\/wp-content\/uploads\/2018\/12\/seismosoft-logox2.webp","contentUrl":"https:\/\/seismosoft.com\/wp-content\/uploads\/2018\/12\/seismosoft-logox2.webp","width":406,"height":100,"caption":"Seismosoft"},"image":{"@id":"https:\/\/seismosoft.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seismoSoft\/","https:\/\/x.com\/Seismosoft","https:\/\/www.linkedin.com\/company\/seismosoft","https:\/\/www.youtube.com\/c\/Seismosoft"]}]}},"_links":{"self":[{"href":"https:\/\/seismosoft.com\/it\/wp-json\/wp\/v2\/product\/20091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seismosoft.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/seismosoft.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seismosoft.com\/it\/wp-json\/wp\/v2\/media\/19676"}],"wp:attachment":[{"href":"https:\/\/seismosoft.com\/it\/wp-json\/wp\/v2\/media?parent=20091"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/seismosoft.com\/it\/wp-json\/wp\/v2\/product_brand?post=20091"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/seismosoft.com\/it\/wp-json\/wp\/v2\/product_cat?post=20091"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/seismosoft.com\/it\/wp-json\/wp\/v2\/product_tag?post=20091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}